
{"id":20,"count":4,"description":"","link":"https:\/\/cimti.cat\/es\/category\/novetats\/","name":"Noticias","slug":"novetats","taxonomy":"category","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/cimti.cat\/es\/wp-json\/wp\/v2\/categories\/20"}],"collection":[{"href":"https:\/\/cimti.cat\/es\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/cimti.cat\/es\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/cimti.cat\/es\/wp-json\/wp\/v2\/posts?categories=20"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}